{"id":10199,"date":"2026-04-21T02:21:50","date_gmt":"2026-04-21T06:21:50","guid":{"rendered":"https:\/\/savoureaston.ca\/?post_type=article&#038;p=10199"},"modified":"2026-04-21T02:21:57","modified_gmt":"2026-04-21T06:21:57","slug":"souffle-au-fromage","status":"publish","type":"article","link":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/","title":{"rendered":"Souffl\u00e9 au fromage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10199\" class=\"elementor elementor-10199 elementor-10090\" data-elementor-post-type=\"article\">\n\t\t\t\t<div class=\"elementor-element elementor-element-728510a e-flex e-con-boxed e-con e-parent\" data-id=\"728510a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-240656a elementor-widget elementor-widget-text-editor\" data-id=\"240656a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ingr\u00e9dients :<\/strong><\/p><p><span style=\"font-size: 17.6px;\">1 once (28 grammes) de parmesan r\u00e2p\u00e9 (1\/2 tasse)<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u00bc tasse (1 1\/4 onces\/35 grammes) de farine tout usage<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u00bc de cuill\u00e8re \u00e0 caf\u00e9 de paprika<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u00bc de cuill\u00e8re \u00e0 caf\u00e9 de sel<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre de Cayenne<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre blanc<\/span><\/p><p><span style=\"font-size: 17.6px;\">Une pinc\u00e9e de noix de muscade moulue<\/span><\/p><p><span style=\"font-size: 17.6px;\">4 cuill\u00e8res \u00e0 soupe de beurre non sal\u00e9<\/span><\/p><p><span style=\"font-size: 17.6px;\">1 \u2153 tasse de lait entier<\/span><\/p><p><span style=\"font-size: 17.6px;\">6 onces (170 grammes) de fromage Gruy\u00e8re, r\u00e2p\u00e9 (1 1\/2 tasse)<\/span><\/p><p><span style=\"font-size: 17.6px;\">6 gros \u0153ufs, s\u00e9par\u00e9s<\/span><\/p><p><span style=\"font-size: 17.6px;\">2 cuill\u00e8res \u00e0 caf\u00e9 de persil frais hach\u00e9<\/span><\/p><p><span style=\"font-size: 17.6px;\">\u00bc de cuill\u00e8re \u00e0 caf\u00e9 de cr\u00e8me de tartre<\/span><\/p><p> <\/p><p><strong><span style=\"font-size: 17.6px;\">Recette :<\/span><\/strong><\/p><p><span style=\"font-size: 17.6px;\">R\u00e9gler la grille du four en position centrale et chauffer le four \u00e0 350 degr\u00e9s. Vaporiser un moule \u00e0 souffl\u00e9 rond de 8 pouces (2 pintes) avec de l&rsquo;huile v\u00e9g\u00e9tale en a\u00e9rosol, puis le saupoudrer de 2 cuill\u00e8res \u00e0 soupe de parmesan. <\/span><\/p><p><span style=\"font-size: 17.6px;\">M\u00e9langer la farine, le paprika, le sel, le poivre de Cayenne, le poivre blanc et la noix de muscade dans un bol. Faire fondre le beurre dans une petite casserole \u00e0 feu moyen. Incorporer le m\u00e9lange de farine et faire cuire pendant 1 minute. Incorporer lentement le lait en fouettant et porter \u00e0 \u00e9bullition. Cuire, en fouettant constamment, jusqu&rsquo;\u00e0 ce que le m\u00e9lange \u00e9paississe et devienne lisse, pendant environ 1 minute. Retirez la po\u00eale du feu et incorporez le Gruy\u00e8re et 5 cuill\u00e8res \u00e0 soupe de Parmesan jusqu&rsquo;\u00e0 ce qu&rsquo;ils soient fondus et lisses. Laissez refroidir pendant 10 minutes, puis incorporez les jaunes d&rsquo;\u0153ufs et 1\u00bd cuill\u00e8re \u00e0 caf\u00e9 de persil en fouettant.      <\/span><\/p><p><span style=\"font-size: 17.6px;\">\u00c0 l&rsquo;aide d&rsquo;un batteur sur socle muni d&rsquo;un fouet, fouetter les blancs d&rsquo;\u0153ufs et la cr\u00e8me de tartre \u00e0 vitesse moyenne-faible jusqu&rsquo;\u00e0 ce qu&rsquo;ils soient mousseux, environ 1 minute. Augmentez la vitesse \u00e0 moyenne-\u00e9lev\u00e9e et fouettez jusqu&rsquo;\u00e0 l&rsquo;obtention de pics fermes, 3 \u00e0 4 minutes. Ajoutez le m\u00e9lange de fromage et continuez \u00e0 fouetter jusqu&rsquo;\u00e0 ce qu&rsquo;il soit enti\u00e8rement combin\u00e9, environ 15 secondes.  <\/span><\/p><p> <\/p><p><span style=\"font-size: 17.6px;\">Verser le m\u00e9lange dans le plat pr\u00e9par\u00e9 et saupoudrer d&rsquo;une cuill\u00e8re \u00e0 soupe de parmesan restante. Cuire au four jusqu&rsquo;\u00e0 ce que la p\u00e2te ait d\u00e9pass\u00e9 le bord, que le dessus soit d&rsquo;un brun dor\u00e9 profond et que l&rsquo;int\u00e9rieur atteigne une temp\u00e9rature de 170 degr\u00e9s, soit 30 \u00e0 35 minutes. Saupoudrez de la \u00bd cuill\u00e8re \u00e0 caf\u00e9 de persil restante et servez imm\u00e9diatement.  <\/span><\/p><p><a href=\"https:\/\/www.americastestkitchen.com\/recipes\/7670-cheese-souffle\"><span style=\"font-size: 1.1em;\">Merci \u00e0 America&rsquo;s Test Kitchen  <\/span><\/a><\/p><p><span style=\"font-size: 17.6px;\"> <\/span><\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ingr\u00e9dients : 1 once (28 grammes) de parmesan r\u00e2p\u00e9 (1\/2 tasse) \u00bc tasse (1 1\/4 onces\/35 grammes) de farine tout usage \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de paprika \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de sel \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre de Cayenne \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre blanc Une pinc\u00e9e de [&hellip;]<\/p>\n","protected":false},"featured_media":10092,"template":"","meta":[],"subject":[205,193],"class_list":["post-10199","article","type-article","status-publish","has-post-thumbnail","hentry","subject-recettes-de-nos-producteurs","subject-recipes-from-your-producers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Souffl\u00e9 au fromage - Savour East Ontario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Souffl\u00e9 au fromage - Savour East Ontario\" \/>\n<meta property=\"og:description\" content=\"Ingr\u00e9dients : 1 once (28 grammes) de parmesan r\u00e2p\u00e9 (1\/2 tasse) \u00bc tasse (1 1\/4 onces\/35 grammes) de farine tout usage \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de paprika \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de sel \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre de Cayenne \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre blanc Une pinc\u00e9e de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/\" \/>\n<meta property=\"og:site_name\" content=\"Savour East Ontario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EastON.EstON\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T06:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/savoureaston.ca\/wp-content\/uploads\/2026\/03\/recipecheesesouffle_bites_may26.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/\",\"url\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/\",\"name\":\"Souffl\u00e9 au fromage - Savour East Ontario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/savoureaston.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/recipecheesesouffle_bites_may26.jpg\",\"datePublished\":\"2026-04-21T06:21:50+00:00\",\"dateModified\":\"2026-04-21T06:21:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/savoureaston.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/recipecheesesouffle_bites_may26.jpg\",\"contentUrl\":\"https:\\\/\\\/savoureaston.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/recipecheesesouffle_bites_may26.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Cheese souffle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/article\\\/souffle-au-fromage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Souffl\u00e9 au fromage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/\",\"name\":\"Savour East Ontario\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#organization\",\"name\":\"Eastern Ontario Agri-food Network\",\"url\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/savoureaston.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SE-ON-logo-long-solide.png\",\"contentUrl\":\"https:\\\/\\\/savoureaston.ca\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SE-ON-logo-long-solide.png\",\"width\":2788,\"height\":1376,\"caption\":\"Eastern Ontario Agri-food Network\"},\"image\":{\"@id\":\"https:\\\/\\\/savoureaston.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EastON.EstON\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Souffl\u00e9 au fromage - Savour East Ontario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/","og_locale":"fr_CA","og_type":"article","og_title":"Souffl\u00e9 au fromage - Savour East Ontario","og_description":"Ingr\u00e9dients : 1 once (28 grammes) de parmesan r\u00e2p\u00e9 (1\/2 tasse) \u00bc tasse (1 1\/4 onces\/35 grammes) de farine tout usage \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de paprika \u00bc de cuill\u00e8re \u00e0 caf\u00e9 de sel \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre de Cayenne \u215b de cuill\u00e8re \u00e0 caf\u00e9 de poivre blanc Une pinc\u00e9e de [&hellip;]","og_url":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/","og_site_name":"Savour East Ontario","article_publisher":"https:\/\/www.facebook.com\/EastON.EstON","article_modified_time":"2026-04-21T06:21:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2026\/03\/recipecheesesouffle_bites_may26.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/","url":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/","name":"Souffl\u00e9 au fromage - Savour East Ontario","isPartOf":{"@id":"https:\/\/savoureaston.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/#primaryimage"},"image":{"@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/#primaryimage"},"thumbnailUrl":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2026\/03\/recipecheesesouffle_bites_may26.jpg","datePublished":"2026-04-21T06:21:50+00:00","dateModified":"2026-04-21T06:21:57+00:00","breadcrumb":{"@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/#primaryimage","url":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2026\/03\/recipecheesesouffle_bites_may26.jpg","contentUrl":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2026\/03\/recipecheesesouffle_bites_may26.jpg","width":1280,"height":720,"caption":"Cheese souffle"},{"@type":"BreadcrumbList","@id":"https:\/\/savoureaston.ca\/fr\/article\/souffle-au-fromage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/savoureaston.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Souffl\u00e9 au fromage"}]},{"@type":"WebSite","@id":"https:\/\/savoureaston.ca\/fr\/#website","url":"https:\/\/savoureaston.ca\/fr\/","name":"Savour East Ontario","description":"","publisher":{"@id":"https:\/\/savoureaston.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/savoureaston.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/savoureaston.ca\/fr\/#organization","name":"Eastern Ontario Agri-food Network","url":"https:\/\/savoureaston.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/savoureaston.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2023\/01\/SE-ON-logo-long-solide.png","contentUrl":"https:\/\/savoureaston.ca\/wp-content\/uploads\/2023\/01\/SE-ON-logo-long-solide.png","width":2788,"height":1376,"caption":"Eastern Ontario Agri-food Network"},"image":{"@id":"https:\/\/savoureaston.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EastON.EstON"]}]}},"_links":{"self":[{"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/article\/10199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/types\/article"}],"version-history":[{"count":1,"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/article\/10199\/revisions"}],"predecessor-version":[{"id":10200,"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/article\/10199\/revisions\/10200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/media\/10092"}],"wp:attachment":[{"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/media?parent=10199"}],"wp:term":[{"taxonomy":"subject","embeddable":true,"href":"https:\/\/savoureaston.ca\/fr\/wp-json\/wp\/v2\/subject?post=10199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}